{"id":26,"count":85,"description":"People Photos","link":"https:\/\/www.daphotostudio.com\/blog\/tag\/people\/","name":"People","slug":"people","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>People Archives - DA Photography<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/daphotostudio.com\/blog\/tag\/people\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"People Archives\" \/>\n<meta property=\"og:description\" content=\"People Photos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/daphotostudio.com\/blog\/tag\/people\/\" \/>\n<meta property=\"og:site_name\" content=\"DA Photography\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/tag\\\/people\\\/\",\"url\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/tag\\\/people\\\/\",\"name\":\"People Archives - DA Photography\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/tag\\\/people\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/tag\\\/people\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"People\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/\",\"name\":\"DA Photography - Dragi Andovski | Portrait | Wedding Photographer\",\"description\":\"Dragi Andovski | Portrait | Wedding Photographer\",\"publisher\":{\"@id\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/#organization\",\"name\":\"DA Photography\",\"url\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.daphotostudio.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Signature-DA-Photography-Logo-Small.png\",\"contentUrl\":\"https:\\\/\\\/www.daphotostudio.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Signature-DA-Photography-Logo-Small.png\",\"width\":501,\"height\":500,\"caption\":\"DA Photography\"},\"image\":{\"@id\":\"https:\\\/\\\/daphotostudio.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DAPhotographyPage\",\"https:\\\/\\\/www.instagram.com\\\/daphotostudio\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/dragi-andovski-36138217\",\"https:\\\/\\\/www.pinterest.com\\\/daphotostudio\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"People Archives - DA Photography","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/daphotostudio.com\/blog\/tag\/people\/","og_locale":"en_US","og_type":"article","og_title":"People Archives","og_description":"People Photos","og_url":"https:\/\/daphotostudio.com\/blog\/tag\/people\/","og_site_name":"DA Photography","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/daphotostudio.com\/blog\/tag\/people\/","url":"https:\/\/daphotostudio.com\/blog\/tag\/people\/","name":"People Archives - DA Photography","isPartOf":{"@id":"https:\/\/daphotostudio.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/daphotostudio.com\/blog\/tag\/people\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/daphotostudio.com\/blog\/tag\/people\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/daphotostudio.com\/blog\/"},{"@type":"ListItem","position":2,"name":"People"}]},{"@type":"WebSite","@id":"https:\/\/daphotostudio.com\/blog\/#website","url":"https:\/\/daphotostudio.com\/blog\/","name":"DA Photography - Dragi Andovski | Portrait | Wedding Photographer","description":"Dragi Andovski | Portrait | Wedding Photographer","publisher":{"@id":"https:\/\/daphotostudio.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/daphotostudio.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/daphotostudio.com\/blog\/#organization","name":"DA Photography","url":"https:\/\/daphotostudio.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/daphotostudio.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.daphotostudio.com\/blog\/wp-content\/uploads\/2024\/02\/Signature-DA-Photography-Logo-Small.png","contentUrl":"https:\/\/www.daphotostudio.com\/blog\/wp-content\/uploads\/2024\/02\/Signature-DA-Photography-Logo-Small.png","width":501,"height":500,"caption":"DA Photography"},"image":{"@id":"https:\/\/daphotostudio.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DAPhotographyPage","https:\/\/www.instagram.com\/daphotostudio\/","https:\/\/www.linkedin.com\/in\/dragi-andovski-36138217","https:\/\/www.pinterest.com\/daphotostudio\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.daphotostudio.com\/blog\/wp-json\/wp\/v2\/tags\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.daphotostudio.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.daphotostudio.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.daphotostudio.com\/blog\/wp-json\/wp\/v2\/posts?tags=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}